{"id":53893,"date":"2026-05-02T07:45:44","date_gmt":"2026-05-02T05:45:44","guid":{"rendered":"https:\/\/www.james.eu\/toepassingsgebieden\/desso-vivaldi-colours-1002-9525\/"},"modified":"2026-05-02T07:45:45","modified_gmt":"2026-05-02T05:45:45","slug":"desso-vivaldi-colours-1002-9525","status":"publish","type":"toepassingsgebieden","link":"https:\/\/www.james.eu\/fr\/domaines-dapplication\/desso-vivaldi-colours-1002-9525\/","title":{"rendered":"Desso &#8211; Vivaldi &#8211; colours 1002-9525"},"content":{"rendered":"","protected":false},"featured_media":0,"parent":0,"template":"","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":""},"fabrikant":[1267],"class_list":["post-53893","toepassingsgebieden","type-toepassingsgebieden","status-publish","hentry","fabrikant-desso","entry","owp-thumbs-layout-horizontal","owp-btn-very-big","owp-tabs-layout-vertical","has-no-thumbnails"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.1 (Yoast SEO v25.3.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00e9couvrez nos conseils pour votre Desso Vivaldi - colours 1002-9525 tapis\/moquette<\/title>\n<meta name=\"description\" content=\"James teste pour vous dans notre labo, en collaboration avec de nombreux fabricants, l&#039;applicabilit\u00e9 des produits James sur votre tapis\/moquette.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.james.eu\/fr\/domaines-dapplication\/desso-vivaldi-colours-1002-9525\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desso - Vivaldi - colours 1002-9525\" \/>\n<meta property=\"og:description\" content=\"James teste pour vous dans notre labo, en collaboration avec de nombreux fabricants, l&#039;applicabilit\u00e9 des produits James sur votre tapis\/moquette.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.james.eu\/fr\/domaines-dapplication\/desso-vivaldi-colours-1002-9525\/\" \/>\n<meta property=\"og:site_name\" content=\"James B.V.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/James-BV-380608888706399\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-02T05:45:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.james.eu\/wp-content\/uploads\/2022\/02\/Logo-James-2021-mail-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"404\" \/>\n\t<meta property=\"og:image:height\" content=\"482\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.james.eu\/fr\/domaines-dapplication\/desso-vivaldi-colours-1002-9525\/\",\"url\":\"https:\/\/www.james.eu\/fr\/domaines-dapplication\/desso-vivaldi-colours-1002-9525\/\",\"name\":\"D\u00e9couvrez nos conseils pour votre Desso Vivaldi - colours 1002-9525 tapis\/moquette\",\"isPartOf\":{\"@id\":\"https:\/\/www.james.eu\/fr\/#website\"},\"datePublished\":\"2026-05-02T05:45:44+00:00\",\"dateModified\":\"2026-05-02T05:45:45+00:00\",\"description\":\"James teste pour vous dans notre labo, en collaboration avec de nombreux fabricants, l'applicabilit\u00e9 des produits James sur votre tapis\/moquette.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.james.eu\/fr\/domaines-dapplication\/desso-vivaldi-colours-1002-9525\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.james.eu\/fr\/domaines-dapplication\/desso-vivaldi-colours-1002-9525\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.james.eu\/fr\/domaines-dapplication\/desso-vivaldi-colours-1002-9525\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.james.eu\/fr\/page-daccueil-fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Domaines D'application\",\"item\":\"https:\/\/www.james.eu\/fr\/domaines-dapplication\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Desso\",\"item\":\"https:\/\/www.james.eu\/fr\/fabricant\/desso\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Desso &#8211; Vivaldi &#8211; colours 1002-9525\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.james.eu\/fr\/#website\",\"url\":\"https:\/\/www.james.eu\/fr\/\",\"name\":\"James B.V.\",\"description\":\"The Finishing Touch\",\"publisher\":{\"@id\":\"https:\/\/www.james.eu\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.james.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.james.eu\/fr\/#organization\",\"name\":\"James B.V.\",\"url\":\"https:\/\/www.james.eu\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.james.eu\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.james.eu\/wp-content\/uploads\/2022\/02\/Logo-James-2021-mail-2.png\",\"contentUrl\":\"https:\/\/www.james.eu\/wp-content\/uploads\/2022\/02\/Logo-James-2021-mail-2.png\",\"width\":404,\"height\":482,\"caption\":\"James B.V.\"},\"image\":{\"@id\":\"https:\/\/www.james.eu\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/James-BV-380608888706399\",\"https:\/\/www.instagram.com\/james.eu1927\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"D\u00e9couvrez nos conseils pour votre Desso Vivaldi - colours 1002-9525 tapis\/moquette","description":"James teste pour vous dans notre labo, en collaboration avec de nombreux fabricants, l'applicabilit\u00e9 des produits James sur votre tapis\/moquette.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.james.eu\/fr\/domaines-dapplication\/desso-vivaldi-colours-1002-9525\/","og_locale":"fr_FR","og_type":"article","og_title":"Desso - Vivaldi - colours 1002-9525","og_description":"James teste pour vous dans notre labo, en collaboration avec de nombreux fabricants, l'applicabilit\u00e9 des produits James sur votre tapis\/moquette.","og_url":"https:\/\/www.james.eu\/fr\/domaines-dapplication\/desso-vivaldi-colours-1002-9525\/","og_site_name":"James B.V.","article_publisher":"https:\/\/www.facebook.com\/James-BV-380608888706399","article_modified_time":"2026-05-02T05:45:45+00:00","og_image":[{"width":404,"height":482,"url":"https:\/\/www.james.eu\/wp-content\/uploads\/2022\/02\/Logo-James-2021-mail-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.james.eu\/fr\/domaines-dapplication\/desso-vivaldi-colours-1002-9525\/","url":"https:\/\/www.james.eu\/fr\/domaines-dapplication\/desso-vivaldi-colours-1002-9525\/","name":"D\u00e9couvrez nos conseils pour votre Desso Vivaldi - colours 1002-9525 tapis\/moquette","isPartOf":{"@id":"https:\/\/www.james.eu\/fr\/#website"},"datePublished":"2026-05-02T05:45:44+00:00","dateModified":"2026-05-02T05:45:45+00:00","description":"James teste pour vous dans notre labo, en collaboration avec de nombreux fabricants, l'applicabilit\u00e9 des produits James sur votre tapis\/moquette.","breadcrumb":{"@id":"https:\/\/www.james.eu\/fr\/domaines-dapplication\/desso-vivaldi-colours-1002-9525\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.james.eu\/fr\/domaines-dapplication\/desso-vivaldi-colours-1002-9525\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.james.eu\/fr\/domaines-dapplication\/desso-vivaldi-colours-1002-9525\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.james.eu\/fr\/page-daccueil-fr\/"},{"@type":"ListItem","position":2,"name":"Domaines D'application","item":"https:\/\/www.james.eu\/fr\/domaines-dapplication\/"},{"@type":"ListItem","position":3,"name":"Desso","item":"https:\/\/www.james.eu\/fr\/fabricant\/desso\/"},{"@type":"ListItem","position":4,"name":"Desso &#8211; Vivaldi &#8211; colours 1002-9525"}]},{"@type":"WebSite","@id":"https:\/\/www.james.eu\/fr\/#website","url":"https:\/\/www.james.eu\/fr\/","name":"James B.V.","description":"The Finishing Touch","publisher":{"@id":"https:\/\/www.james.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.james.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.james.eu\/fr\/#organization","name":"James B.V.","url":"https:\/\/www.james.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.james.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.james.eu\/wp-content\/uploads\/2022\/02\/Logo-James-2021-mail-2.png","contentUrl":"https:\/\/www.james.eu\/wp-content\/uploads\/2022\/02\/Logo-James-2021-mail-2.png","width":404,"height":482,"caption":"James B.V."},"image":{"@id":"https:\/\/www.james.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/James-BV-380608888706399","https:\/\/www.instagram.com\/james.eu1927\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.james.eu\/fr\/wp-json\/wp\/v2\/toepassingsgebieden\/53893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.james.eu\/fr\/wp-json\/wp\/v2\/toepassingsgebieden"}],"about":[{"href":"https:\/\/www.james.eu\/fr\/wp-json\/wp\/v2\/types\/toepassingsgebieden"}],"wp:attachment":[{"href":"https:\/\/www.james.eu\/fr\/wp-json\/wp\/v2\/media?parent=53893"}],"wp:term":[{"taxonomy":"fabrikant","embeddable":true,"href":"https:\/\/www.james.eu\/fr\/wp-json\/wp\/v2\/fabrikant?post=53893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}