{"id":57064,"date":"2021-09-14T10:06:17","date_gmt":"2021-09-14T10:06:17","guid":{"rendered":"https:\/\/www.james.eu\/faq\/la-tache-sen-va-mais-revient-sans-cesse\/"},"modified":"2023-01-27T15:17:55","modified_gmt":"2023-01-27T14:17:55","slug":"la-tache-sen-va-mais-revient-sans-cesse","status":"publish","type":"faq","link":"https:\/\/www.james.eu\/fr\/faq\/la-tache-sen-va-mais-revient-sans-cesse\/","title":{"rendered":"La tache s&rsquo;\u00e9teint mais revient sans cesse"},"content":{"rendered":"","protected":false},"template":"","class_list":["post-57064","faq","type-faq","status-publish","hentry","entry","owp-thumbs-layout-horizontal","owp-btn-very-big","owp-tabs-layout-vertical","has-no-thumbnails"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.1 (Yoast SEO v25.3.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La tache s&#039;\u00e9teint mais revient sans cesse - James sait ce qu&#039;il faut faire!<\/title>\n<meta name=\"description\" content=\"Souffrez-vous \u00e9galement de boutons qui reviennent constamment? Alors lisez la suite.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.james.eu\/fr\/faq\/la-tache-sen-va-mais-revient-sans-cesse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La tache s&#039;\u00e9teint mais revient sans cesse\" \/>\n<meta property=\"og:description\" content=\"Souffrez-vous \u00e9galement de boutons qui reviennent constamment? Alors lisez la suite.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.james.eu\/fr\/faq\/la-tache-sen-va-mais-revient-sans-cesse\/\" \/>\n<meta property=\"og:site_name\" content=\"James B.V.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/James-BV-380608888706399\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-27T14:17:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.james.eu\/wp-content\/uploads\/2022\/02\/Logo-James-2021-mail-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"404\" \/>\n\t<meta property=\"og:image:height\" content=\"482\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.james.eu\/fr\/faq\/la-tache-sen-va-mais-revient-sans-cesse\/\",\"url\":\"https:\/\/www.james.eu\/fr\/faq\/la-tache-sen-va-mais-revient-sans-cesse\/\",\"name\":\"La tache s'\u00e9teint mais revient sans cesse - James sait ce qu'il faut faire!\",\"isPartOf\":{\"@id\":\"https:\/\/www.james.eu\/fr\/#website\"},\"datePublished\":\"2021-09-14T10:06:17+00:00\",\"dateModified\":\"2023-01-27T14:17:55+00:00\",\"description\":\"Souffrez-vous \u00e9galement de boutons qui reviennent constamment? Alors lisez la suite.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.james.eu\/fr\/faq\/la-tache-sen-va-mais-revient-sans-cesse\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.james.eu\/fr\/faq\/la-tache-sen-va-mais-revient-sans-cesse\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.james.eu\/fr\/faq\/la-tache-sen-va-mais-revient-sans-cesse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.james.eu\/fr\/page-daccueil-fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQ\",\"item\":\"https:\/\/www.james.eu\/fr\/faq\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La tache s&rsquo;\u00e9teint mais revient sans cesse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.james.eu\/fr\/#website\",\"url\":\"https:\/\/www.james.eu\/fr\/\",\"name\":\"James B.V.\",\"description\":\"The Finishing Touch\",\"publisher\":{\"@id\":\"https:\/\/www.james.eu\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.james.eu\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.james.eu\/fr\/#organization\",\"name\":\"James B.V.\",\"url\":\"https:\/\/www.james.eu\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.james.eu\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.james.eu\/wp-content\/uploads\/2022\/02\/Logo-James-2021-mail-2.png\",\"contentUrl\":\"https:\/\/www.james.eu\/wp-content\/uploads\/2022\/02\/Logo-James-2021-mail-2.png\",\"width\":404,\"height\":482,\"caption\":\"James B.V.\"},\"image\":{\"@id\":\"https:\/\/www.james.eu\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/James-BV-380608888706399\",\"https:\/\/www.instagram.com\/james.eu1927\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La tache s'\u00e9teint mais revient sans cesse - James sait ce qu'il faut faire!","description":"Souffrez-vous \u00e9galement de boutons qui reviennent constamment? Alors lisez la suite.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.james.eu\/fr\/faq\/la-tache-sen-va-mais-revient-sans-cesse\/","og_locale":"fr_FR","og_type":"article","og_title":"La tache s'\u00e9teint mais revient sans cesse","og_description":"Souffrez-vous \u00e9galement de boutons qui reviennent constamment? Alors lisez la suite.","og_url":"https:\/\/www.james.eu\/fr\/faq\/la-tache-sen-va-mais-revient-sans-cesse\/","og_site_name":"James B.V.","article_publisher":"https:\/\/www.facebook.com\/James-BV-380608888706399","article_modified_time":"2023-01-27T14:17:55+00:00","og_image":[{"width":404,"height":482,"url":"https:\/\/www.james.eu\/wp-content\/uploads\/2022\/02\/Logo-James-2021-mail-2.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.james.eu\/fr\/faq\/la-tache-sen-va-mais-revient-sans-cesse\/","url":"https:\/\/www.james.eu\/fr\/faq\/la-tache-sen-va-mais-revient-sans-cesse\/","name":"La tache s'\u00e9teint mais revient sans cesse - James sait ce qu'il faut faire!","isPartOf":{"@id":"https:\/\/www.james.eu\/fr\/#website"},"datePublished":"2021-09-14T10:06:17+00:00","dateModified":"2023-01-27T14:17:55+00:00","description":"Souffrez-vous \u00e9galement de boutons qui reviennent constamment? Alors lisez la suite.","breadcrumb":{"@id":"https:\/\/www.james.eu\/fr\/faq\/la-tache-sen-va-mais-revient-sans-cesse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.james.eu\/fr\/faq\/la-tache-sen-va-mais-revient-sans-cesse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.james.eu\/fr\/faq\/la-tache-sen-va-mais-revient-sans-cesse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.james.eu\/fr\/page-daccueil-fr\/"},{"@type":"ListItem","position":2,"name":"FAQ","item":"https:\/\/www.james.eu\/fr\/faq\/"},{"@type":"ListItem","position":3,"name":"La tache s&rsquo;\u00e9teint mais revient sans cesse"}]},{"@type":"WebSite","@id":"https:\/\/www.james.eu\/fr\/#website","url":"https:\/\/www.james.eu\/fr\/","name":"James B.V.","description":"The Finishing Touch","publisher":{"@id":"https:\/\/www.james.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.james.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.james.eu\/fr\/#organization","name":"James B.V.","url":"https:\/\/www.james.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.james.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.james.eu\/wp-content\/uploads\/2022\/02\/Logo-James-2021-mail-2.png","contentUrl":"https:\/\/www.james.eu\/wp-content\/uploads\/2022\/02\/Logo-James-2021-mail-2.png","width":404,"height":482,"caption":"James B.V."},"image":{"@id":"https:\/\/www.james.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/James-BV-380608888706399","https:\/\/www.instagram.com\/james.eu1927\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.james.eu\/fr\/wp-json\/wp\/v2\/faq\/57064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.james.eu\/fr\/wp-json\/wp\/v2\/faq"}],"about":[{"href":"https:\/\/www.james.eu\/fr\/wp-json\/wp\/v2\/types\/faq"}],"wp:attachment":[{"href":"https:\/\/www.james.eu\/fr\/wp-json\/wp\/v2\/media?parent=57064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}